{"id":4479,"date":"2021-07-21T11:17:17","date_gmt":"2021-07-21T16:17:17","guid":{"rendered":"https:\/\/rbh-access.com\/password-reset\/"},"modified":"2021-07-21T13:05:05","modified_gmt":"2021-07-21T18:05:05","slug":"password-reset","status":"publish","type":"page","link":"https:\/\/rbh-access.com\/es\/password-reset\/","title":{"rendered":"Restablecimiento de contrase\u00f1a"},"content":{"rendered":"<div class=\"um um-password um-um_password_id\">\n\t<div class=\"um-form\">\n\t\t<form method=\"post\" action=\"\" data-trp-original-action=\"\">\n\t\t\t\n\t\t\t\t<input type=\"hidden\" name=\"_um_password_reset\" id=\"_um_password_reset\" value=\"1\" \/>\n\n\t\t\t\t\t\t\t\t\t<div class=\"um-field um-field-block um-field-type_block\">\n\t\t\t\t\t\t<div class=\"um-field-block\">\n\t\t\t\t\t\t\t<div style=\"text-align:center;\">\n\t\t\t\t\t\t\t\tPara restablecer su contrase\u00f1a, ingrese su direcci\u00f3n de correo electr\u00f3nico o nombre de usuario a continuaci\u00f3n.\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div  id=\"um_field_0_username_b\" class=\"um-field um-field-text  um-field-username_b um-field-text um-field-type_text\" data-key=\"username_b\"><div class=\"um-field-area\"><input  autocomplete=\"off\" class=\"um-form-field valid\" type=\"text\" name=\"username_b\" id=\"username_b\" value=\"\" placeholder=\"Introduzca su nombre de usuario o correo electr\u00f3nico\" data-validate=\"\" data-key=\"username_b\"  aria-invalid=\"false\" \/>\n\n\t\t\t\t\t\t<\/div><\/div>\n<div class=\"g-recaptcha\" id=\"um-um_password_id\" data-mode=\"password\"><\/div>\n\n\t\t\t\t<div class=\"um-col-alt um-col-alt-b\">\n\t\t\t\t\t<div class=\"um-center\">\n\t\t\t\t\t\t<input type=\"submit\" value=\"Restablecer la contrase\u00f1a\" class=\"um-button\" id=\"um-submit-btn\" \/>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"um-clear\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<input type=\"hidden\" name=\"form_id\" id=\"form_id_um_password_id\" value=\"um_password_id\" \/>\n\t\t<p class=\"um_request_name\">\n\t\t<label for=\"um_request_um_password_id\">Rell\u00e9nalo solo si no eres humano<\/label>\n\t\t<input type=\"hidden\" name=\"um_request\" id=\"um_request_um_password_id\" class=\"input\" value=\"\" size=\"25\" autocomplete=\"off\" \/>\n\t<\/p>\n\t\t\t<input type=\"hidden\" name=\"trp-form-language\" value=\"es\"\/><\/form>\n\t<\/div>\n<\/div>\n<style>\n\t\t\t.um-um_password_id.um {\n\t\t\tmax-width: 450px;\n\t\t}\n\t\t<\/style>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"content-type":"","footnotes":""},"class_list":["post-4479","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Password Reset - RBH Access Technologies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rbh-access.com\/es\/password-reset\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Password Reset - RBH Access Technologies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rbh-access.com\/es\/password-reset\/\" \/>\n<meta property=\"og:site_name\" content=\"RBH Access Technologies\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-21T18:05:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rbh-access.com\\\/password-reset\\\/\",\"url\":\"https:\\\/\\\/rbh-access.com\\\/password-reset\\\/\",\"name\":\"Password Reset - RBH Access Technologies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rbh-access.com\\\/#website\"},\"datePublished\":\"2021-07-21T16:17:17+00:00\",\"dateModified\":\"2021-07-21T18:05:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rbh-access.com\\\/password-reset\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rbh-access.com\\\/password-reset\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rbh-access.com\\\/password-reset\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rbh-access.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Password Reset\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rbh-access.com\\\/#website\",\"url\":\"https:\\\/\\\/rbh-access.com\\\/\",\"name\":\"RBH Access Technologies\",\"description\":\"We Are Access Control\",\"publisher\":{\"@id\":\"https:\\\/\\\/rbh-access.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rbh-access.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rbh-access.com\\\/#organization\",\"name\":\"RBH Access Technologies\",\"url\":\"https:\\\/\\\/rbh-access.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rbh-access.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rbh-access.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/log2.png\",\"contentUrl\":\"https:\\\/\\\/rbh-access.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/log2.png\",\"width\":192,\"height\":82,\"caption\":\"RBH Access Technologies\"},\"image\":{\"@id\":\"https:\\\/\\\/rbh-access.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Password Reset - RBH Access Technologies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rbh-access.com\/es\/password-reset\/","og_locale":"es_MX","og_type":"article","og_title":"Password Reset - RBH Access Technologies","og_url":"https:\/\/rbh-access.com\/es\/password-reset\/","og_site_name":"RBH Access Technologies","article_modified_time":"2021-07-21T18:05:05+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rbh-access.com\/password-reset\/","url":"https:\/\/rbh-access.com\/password-reset\/","name":"Password Reset - RBH Access Technologies","isPartOf":{"@id":"https:\/\/rbh-access.com\/#website"},"datePublished":"2021-07-21T16:17:17+00:00","dateModified":"2021-07-21T18:05:05+00:00","breadcrumb":{"@id":"https:\/\/rbh-access.com\/password-reset\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rbh-access.com\/password-reset\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rbh-access.com\/password-reset\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rbh-access.com\/"},{"@type":"ListItem","position":2,"name":"Password Reset"}]},{"@type":"WebSite","@id":"https:\/\/rbh-access.com\/#website","url":"https:\/\/rbh-access.com\/","name":"RBH Access Technologies","description":"We Are Access Control","publisher":{"@id":"https:\/\/rbh-access.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rbh-access.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/rbh-access.com\/#organization","name":"RBH Access Technologies","url":"https:\/\/rbh-access.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rbh-access.com\/#\/schema\/logo\/image\/","url":"https:\/\/rbh-access.com\/wp-content\/uploads\/2021\/03\/log2.png","contentUrl":"https:\/\/rbh-access.com\/wp-content\/uploads\/2021\/03\/log2.png","width":192,"height":82,"caption":"RBH Access Technologies"},"image":{"@id":"https:\/\/rbh-access.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rbh-access.com\/es\/wp-json\/wp\/v2\/pages\/4479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rbh-access.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rbh-access.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rbh-access.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rbh-access.com\/es\/wp-json\/wp\/v2\/comments?post=4479"}],"version-history":[{"count":0,"href":"https:\/\/rbh-access.com\/es\/wp-json\/wp\/v2\/pages\/4479\/revisions"}],"wp:attachment":[{"href":"https:\/\/rbh-access.com\/es\/wp-json\/wp\/v2\/media?parent=4479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}